{"id":15791,"date":"2023-08-04T15:42:46","date_gmt":"2023-08-04T08:42:46","guid":{"rendered":"https:\/\/topsvita.com\/cetaphil-gentle-skin-cleanser-125ml\/"},"modified":"2024-04-30T15:17:40","modified_gmt":"2024-04-30T08:17:40","slug":"cetaphil-gentle-skin-cleanser-125ml","status":"publish","type":"product","link":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/","title":{"rendered":"Cetaphil Gentle Skin Cleanser 125ml."},"content":{"rendered":"<p>Cetaphil Cleanser Gentle Skin 125 ml. Gentle formula, soap and fragrance free, can be used daily without irritating the skin, easy to wash off, retain moisture. Makes skin soft, smooth and strong. It can be used to clean even baby&#8217;s skin. Suitable for both face and body use.<br \/>\nFDA No. 10-2-5703637<\/p>\n<p>Use water to rinse, apply and massage Cetaphil over the area that needs cleaning. Then rinse with clean water<br \/>\nDo not use water to rinse, apply and massage Cetaphil over the area that needs to be cleaned. Then use a clean cloth, tissue or cotton swab to wipe it off. A thin film of Cetaphil will coat the skin.<br \/>\nTo maintain moisture and softness of the skin<br \/>\nUse to wipe clean cosmetics, rub, massage Cetaphil over the face and use cotton to wipe off. Or you can pour Cetaphil on a cotton ball. And gently wipe the makeup off<br \/>\nFDA No. 10-2-6500004036<\/p>\n","protected":false},"excerpt":{"rendered":"<h2 class=\"thin-font\"><span style=\"font-size: 50%;\" data-line-height=\"xs\">Shop Cetaphil Gentle Skin Cleanser 125ml. online now&#8230;<\/span><\/h2>\n<p><a class=\"click_lzd\" href=\"https:\/\/c.lazada.co.th\/t\/c.Yb3o5k?intent=false&amp;fallback=true&amp;url=https%3A%2F%2Fwww.lazada.co.th%2Fproducts%2Fi4805164889.html\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-1451\" src=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/LZD-tops-vita.webp\" alt=\"Lazada \u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 Tops Vita\" width=\"50\" height=\"50\" srcset=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/LZD-tops-vita.webp 200w, https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/LZD-tops-vita-150x150.webp 150w, https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/LZD-tops-vita-100x100.webp 100w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a> <a class=\"click_shp\" href=\"https:\/\/shopee.co.th\/product\/918925876\/23275445679?smtt=9&amp;utm_source=website&amp;utm_medium=seller&amp;utm_campaign=s918925876_SS_SG_WEBS_3499320013055&amp;utm_content=&amp;deep_and_web=1\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-1452\" src=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Shopee-tops-vita.webp\" alt=\"Shopee \u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 Tops Vita\" width=\"50\" height=\"50\" srcset=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Shopee-tops-vita.webp 200w, https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Shopee-tops-vita-150x150.webp 150w, https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Shopee-tops-vita-100x100.webp 100w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><\/p>\n<h2 class=\"thin-font\"><span style=\"font-size: 50%;\" data-line-height=\"xs\">Chat with us on LINE@ Tops Vita<\/span><\/h2>\n<p><a href=\"https:\/\/page.line.me\/129xhigy?openQrModal=true\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-1454\" src=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Line-chat-shop-tops-vita.webp\" alt=\"Line Chat Shop Tops Vita\" width=\"164\" height=\"42\" srcset=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Line-chat-shop-tops-vita.webp 500w, https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Line-chat-shop-tops-vita-300x77.webp 300w\" sizes=\"(max-width: 164px) 100vw, 164px\" \/><\/a><\/p>\n","protected":false},"featured_media":9653,"template":"","meta":[],"product_cat":[448,502,503,518],"product_tag":[],"class_list":["post-15791","product","type-product","status-publish","has-post-thumbnail","product_cat-adults","product_cat-cosmecuetical","product_cat-facial-care","product_cat-skin-beauty","pa_brands-cetaphil","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32<\/title>\n<meta name=\"description\" content=\"Tops Vita \u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d Cetaphil Gentle Skin Cleanser 125ml. \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32\" \/>\n<meta property=\"og:description\" content=\"Tops Vita \u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d Cetaphil Gentle Skin Cleanser 125ml. \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-30T08:17:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/08\/3499320013055_topsvita_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/\",\"url\":\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/\",\"name\":\"\u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32\",\"isPartOf\":{\"@id\":\"https:\/\/topsvita.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/07\/3499320013055_topsvita_01.jpg\",\"datePublished\":\"2023-08-04T08:42:46+00:00\",\"dateModified\":\"2024-04-30T08:17:40+00:00\",\"description\":\"Tops Vita \u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d Cetaphil Gentle Skin Cleanser 125ml. \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\",\"breadcrumb\":{\"@id\":\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#primaryimage\",\"url\":\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/07\/3499320013055_topsvita_01.jpg\",\"contentUrl\":\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/07\/3499320013055_topsvita_01.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/topsvita.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/topsvita.com\/?page_id=8\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cetaphil Gentle Skin Cleanser 125ml.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/topsvita.com\/en\/#website\",\"url\":\"https:\/\/topsvita.com\/en\/\",\"name\":\"Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32\",\"description\":\"\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13 Tops Vita\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/topsvita.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","description":"Tops Vita \u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d Cetaphil Gentle Skin Cleanser 125ml. \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/","og_locale":"en_US","og_type":"article","og_title":"\u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","og_description":"Tops Vita \u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d Cetaphil Gentle Skin Cleanser 125ml. \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19","og_url":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/","og_site_name":"Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","article_modified_time":"2024-04-30T08:17:40+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/08\/3499320013055_topsvita_01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/","url":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/","name":"\u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","isPartOf":{"@id":"https:\/\/topsvita.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#primaryimage"},"image":{"@id":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#primaryimage"},"thumbnailUrl":"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/07\/3499320013055_topsvita_01.jpg","datePublished":"2023-08-04T08:42:46+00:00","dateModified":"2024-04-30T08:17:40+00:00","description":"Tops Vita \u0e02\u0e32\u0e22 Cetaphil Gentle Skin Cleanser 125ml. \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d Cetaphil Gentle Skin Cleanser 125ml. \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19","breadcrumb":{"@id":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#primaryimage","url":"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/07\/3499320013055_topsvita_01.jpg","contentUrl":"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/07\/3499320013055_topsvita_01.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/topsvita.com\/en\/cetaphil-gentle-skin-cleanser-125ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/topsvita.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/topsvita.com\/?page_id=8"},{"@type":"ListItem","position":3,"name":"Cetaphil Gentle Skin Cleanser 125ml."}]},{"@type":"WebSite","@id":"https:\/\/topsvita.com\/en\/#website","url":"https:\/\/topsvita.com\/en\/","name":"Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","description":"\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13 Tops Vita","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/topsvita.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/product\/15791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/media\/9653"}],"wp:attachment":[{"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/media?parent=15791"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/product_cat?post=15791"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/product_tag?post=15791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}