{"id":12708,"date":"2023-06-30T17:06:43","date_gmt":"2023-06-30T10:06:43","guid":{"rendered":"https:\/\/topsvita.com\/imural-dietary-supplement-product-30capsules\/"},"modified":"2025-01-08T18:19:52","modified_gmt":"2025-01-08T11:19:52","slug":"imural-dietary-supplement-product-30capsules","status":"publish","type":"product","link":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/","title":{"rendered":"\u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25"},"content":{"rendered":"<p><strong>IMURAL<\/strong> \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25<\/p>\n<hr \/>\n<p><strong>\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19 \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 1 \u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25\u00a0 :<\/strong><br \/>\n&#8211; \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e39\u0e04\u0e32\u0e27 100 \u0e21\u0e01.<br \/>\n&#8211; \u0e41\u0e2d\u0e25-\u0e01\u0e25\u0e39\u0e15\u0e32\u0e44\u0e18\u0e42\u0e2d\u0e19 100 \u0e21\u0e01.<br \/>\n&#8211; \u0e40\u0e1a\u0e15\u0e49\u0e32 \u0e01\u0e25\u0e39\u0e41\u0e04\u0e19 \u0e08\u0e32\u0e01\u0e1a\u0e23\u0e39\u0e40\u0e2a\u0e2d\u0e23\u0e4c\u0e2a\u0e22\u0e35\u0e2a\u0e15\u0e4c 60 \u0e21\u0e01.<br \/>\n&#8211; \u0e42\u0e04\u0e25\u0e35\u0e19 \u0e44\u0e1a\u0e17\u0e32\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e15 40 \u0e21\u0e01.<br \/>\n&#8211; \u0e0b\u0e34\u0e07\u0e04\u0e4c \u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19 \u0e41\u0e2d\u0e0b\u0e34\u0e14 \u0e04\u0e35\u0e40\u0e25\u0e15 20% 15 \u0e21\u0e01.<br \/>\n&#8211; \u0e41\u0e2d\u0e25-\u0e0b\u0e34\u0e2a\u0e40\u0e17\u0e2d\u0e35\u0e19 \u0e44\u0e2e\u0e42\u0e14\u0e23\u0e04\u0e25\u0e2d\u0e44\u0e23\u0e14\u0e4c 10 \u0e21\u0e01.<br \/>\n&#8211; \u0e44\u0e01\u0e25\u0e0b\u0e35\u0e19 10 \u0e21\u0e01.<br \/>\n&#8211; \u0e41\u0e2d\u0e25-\u0e01\u0e25\u0e39\u0e15\u0e32\u0e21\u0e35\u0e19 10 \u0e21\u0e01.<br \/>\n&#8211; \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e2d\u0e35 50% 10 \u0e21\u0e01.<br \/>\n&#8211; \u0e04\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19 \u0e41\u0e2d\u0e0b\u0e34\u0e14 \u0e04\u0e35\u0e40\u0e25\u0e15 10% 10 \u0e21\u0e01.<br \/>\n&#8211; \u0e0b\u0e35\u0e25\u0e35\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19 \u0e41\u0e2d\u0e0b\u0e34\u0e14 \u0e04\u0e35\u0e40\u0e25\u0e15 0.2% 7 \u0e21\u0e01.<br \/>\n&#8211; \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e1a\u0e35 6 1 \u0e21\u0e01.<br \/>\n&#8211; \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e1a\u0e35 1 0.75 \u0e21\u0e01.<br \/>\n&#8211; \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e1a\u0e35 2 0.75 \u0e21\u0e01.<br \/>\n&#8211; \u0e01\u0e23\u0e14\u0e42\u0e1f\u0e25\u0e34\u0e04 0.1 \u0e21\u0e01.<br \/>\n&#8211; \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e1a\u0e35 12 0.002 \u0e21\u0e01.<\/p>\n<hr \/>\n<p><strong>\u0e27\u0e34\u0e18\u0e35\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 :<\/strong><br \/>\n&#8211; \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e27\u0e31\u0e19\u0e25\u0e30 1 \u0e40\u0e21\u0e47\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e19\u0e2d\u0e19<\/p>\n<hr \/>\n<p><strong>\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 :<\/strong><br \/>\n&#8211; \u0e04\u0e27\u0e23\u0e01\u0e34\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e1a 5 \u0e2b\u0e21\u0e39\u0e48 \u0e43\u0e19\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33<\/p>\n<hr \/>\n<p><strong>\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e2d\u0e22. :<\/strong><br \/>\n&#8211; 11-1-13958-5-0081<\/p>\n","protected":false},"excerpt":{"rendered":"<h2 class=\"thin-font\"><span style=\"font-size: 50%;\" data-line-height=\"xs\">\u0e0a\u0e49\u0e2d\u0e1b Imural 30capsules \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48&#8230;<\/span><\/h2>\n<p><a class=\"click_lzd\" href=\"https:\/\/c.lazada.co.th\/t\/c.Y0qQUy?intent=false&#038;fallback=true&#038;url=https%3A%2F%2Fwww.lazada.co.th%2Fproducts%2Fi4560372272.html%3FurlFlag%3Dtrue\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-1451\" src=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/LZD-tops-vita.webp\" alt=\"Lazada \u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 Tops Vita\" width=\"50\" height=\"50\" srcset=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/LZD-tops-vita.webp 200w, https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/LZD-tops-vita-150x150.webp 150w, https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/LZD-tops-vita-100x100.webp 100w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a> <a class=\"click_shp\" href=\"https:\/\/shopee.co.th\/product\/918925876\/18678349971?smtt=9&#038;utm_source=website&#038;utm_medium=seller&#038;utm_campaign=s918925876_SS_SG_WEBS_website-topsvita&#038;utm_content=8855641002416&#038;deep_and_web=1\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-1452\" src=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Shopee-tops-vita.webp\" alt=\"Shopee \u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 Tops Vita\" width=\"50\" height=\"50\" srcset=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Shopee-tops-vita.webp 200w, https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Shopee-tops-vita-150x150.webp 150w, https:\/\/topsvita.com\/wp-content\/uploads\/2023\/05\/Shopee-tops-vita-100x100.webp 100w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a> <\/p>\n","protected":false},"featured_media":6493,"template":"","meta":[],"product_cat":[448,476,470,520],"product_tag":[],"class_list":{"0":"post-12708","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-adults","7":"product_cat-ayurvedic-herbs","8":"product_cat-herbal-plant-extract-category","9":"product_cat-immunity","10":"pa_brands-imural","12":"first","13":"instock","14":"shipping-taxable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e02\u0e32\u0e22 \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32<\/title>\n<meta name=\"description\" content=\"Tops Vita \u0e02\u0e32\u0e22 Imural \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e02\u0e32\u0e22 \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32\" \/>\n<meta property=\"og:description\" content=\"Tops Vita \u0e02\u0e32\u0e22 Imural \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/\" \/>\n<meta property=\"og:site_name\" content=\"Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-08T11:19:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/06\/8855641002416_topsvita_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/\",\"url\":\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/\",\"name\":\"\u0e02\u0e32\u0e22 \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32\",\"isPartOf\":{\"@id\":\"https:\/\/topsvita.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/06\/8855641002416_topsvita_01.jpg\",\"datePublished\":\"2023-06-30T10:06:43+00:00\",\"dateModified\":\"2025-01-08T11:19:52+00:00\",\"description\":\"Tops Vita \u0e02\u0e32\u0e22 Imural \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\",\"breadcrumb\":{\"@id\":\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#primaryimage\",\"url\":\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/06\/8855641002416_topsvita_01.jpg\",\"contentUrl\":\"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/06\/8855641002416_topsvita_01.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"\u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/topsvita.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/topsvita.com\/?page_id=8\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/topsvita.com\/en\/#website\",\"url\":\"https:\/\/topsvita.com\/en\/\",\"name\":\"Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32\",\"description\":\"\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13 Tops Vita\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/topsvita.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e02\u0e32\u0e22 \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","description":"Tops Vita \u0e02\u0e32\u0e22 Imural \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/","og_locale":"en_US","og_type":"article","og_title":"\u0e02\u0e32\u0e22 \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","og_description":"Tops Vita \u0e02\u0e32\u0e22 Imural \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19","og_url":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/","og_site_name":"Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","article_modified_time":"2025-01-08T11:19:52+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/06\/8855641002416_topsvita_01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/","url":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/","name":"\u0e02\u0e32\u0e22 \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 | Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","isPartOf":{"@id":"https:\/\/topsvita.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#primaryimage"},"image":{"@id":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#primaryimage"},"thumbnailUrl":"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/06\/8855641002416_topsvita_01.jpg","datePublished":"2023-06-30T10:06:43+00:00","dateModified":"2025-01-08T11:19:52+00:00","description":"Tops Vita \u0e02\u0e32\u0e22 Imural \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e09\u0e31\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19","breadcrumb":{"@id":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#primaryimage","url":"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/06\/8855641002416_topsvita_01.jpg","contentUrl":"https:\/\/topsvita.com\/wp-content\/uploads\/2023\/06\/8855641002416_topsvita_01.jpg","width":1200,"height":1200,"caption":"\u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25"},{"@type":"BreadcrumbList","@id":"https:\/\/topsvita.com\/en\/imural-dietary-supplement-product-30capsules\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/topsvita.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/topsvita.com\/?page_id=8"},{"@type":"ListItem","position":3,"name":"\u0e2d\u0e34\u0e21\u0e39\u0e23\u0e2d\u0e25 30\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e25"}]},{"@type":"WebSite","@id":"https:\/\/topsvita.com\/en\/#website","url":"https:\/\/topsvita.com\/en\/","name":"Tops Vita \u0e17\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e27\u0e35\u0e15\u0e49\u0e32","description":"\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e21\u0e35 \u0e2d\u0e22. \u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13 Tops Vita","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/topsvita.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/product\/12708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/media\/6493"}],"wp:attachment":[{"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/media?parent=12708"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/product_cat?post=12708"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/topsvita.com\/en\/wp-json\/wp\/v2\/product_tag?post=12708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}